{"id":54,"count":0,"description":"","link":"https:\/\/www.iespm.fr\/en\/category\/special-report\/","name":"Special report","slug":"special-report","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Special report - IESPM - Laboratoire d&#039;analyse de fluides et lubrifiants<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iespm.fr\/en\/category\/special-report\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Special report - IESPM - Laboratoire d&#039;analyse de fluides et lubrifiants\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iespm.fr\/en\/category\/special-report\/\" \/>\n<meta property=\"og:site_name\" content=\"IESPM - Laboratoire d&#039;analyse de fluides et lubrifiants\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/category\\\/special-report\\\/\",\"url\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/category\\\/special-report\\\/\",\"name\":\"Archives des Special report - IESPM - Laboratoire d&#039;analyse de fluides et lubrifiants\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/category\\\/special-report\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/category\\\/special-report\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Special report\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/\",\"name\":\"IESPM - Laboratoire analyse de fluides et lubrifiants\",\"description\":\"Laboratoire d&#039;analyse de fluides et lubrifiants\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/#organization\",\"name\":\"IESPM - Laboratoire analyse de fluides et lubrifiants\",\"url\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iespm.fr\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IESPM_logo-png.png\",\"contentUrl\":\"https:\\\/\\\/www.iespm.fr\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/IESPM_logo-png.png\",\"width\":871,\"height\":188,\"caption\":\"IESPM - Laboratoire analyse de fluides et lubrifiants\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iespm.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/eurofins-iespm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@EurofinsIESPM\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Special report - IESPM - Laboratoire d&#039;analyse de fluides et lubrifiants","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iespm.fr\/en\/category\/special-report\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Special report - IESPM - Laboratoire d&#039;analyse de fluides et lubrifiants","og_url":"https:\/\/www.iespm.fr\/en\/category\/special-report\/","og_site_name":"IESPM - Laboratoire d&#039;analyse de fluides et lubrifiants","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.iespm.fr\/en\/category\/special-report\/","url":"https:\/\/www.iespm.fr\/en\/category\/special-report\/","name":"Archives des Special report - IESPM - Laboratoire d&#039;analyse de fluides et lubrifiants","isPartOf":{"@id":"https:\/\/www.iespm.fr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.iespm.fr\/en\/category\/special-report\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iespm.fr\/en\/category\/special-report\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.iespm.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Special report"}]},{"@type":"WebSite","@id":"https:\/\/www.iespm.fr\/en\/#website","url":"https:\/\/www.iespm.fr\/en\/","name":"IESPM - Laboratoire analyse de fluides et lubrifiants","description":"Laboratoire d&#039;analyse de fluides et lubrifiants","publisher":{"@id":"https:\/\/www.iespm.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iespm.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.iespm.fr\/en\/#organization","name":"IESPM - Laboratoire analyse de fluides et lubrifiants","url":"https:\/\/www.iespm.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.iespm.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.iespm.fr\/wp-content\/uploads\/2022\/10\/IESPM_logo-png.png","contentUrl":"https:\/\/www.iespm.fr\/wp-content\/uploads\/2022\/10\/IESPM_logo-png.png","width":871,"height":188,"caption":"IESPM - Laboratoire analyse de fluides et lubrifiants"},"image":{"@id":"https:\/\/www.iespm.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/eurofins-iespm\/","https:\/\/www.youtube.com\/@EurofinsIESPM"]}]}},"_links":{"self":[{"href":"https:\/\/www.iespm.fr\/en\/wp-json\/wp\/v2\/categories\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iespm.fr\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.iespm.fr\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.iespm.fr\/en\/wp-json\/wp\/v2\/posts?categories=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}